{"id":87,"count":1,"description":"","link":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/","name":"dialogue","slug":"dialogue","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>dialogue Archives - Arcanoria Games<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dialogue Archives - Arcanoria Games\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcanoria Games\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/tag\\\/dialogue\\\/\",\"url\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/tag\\\/dialogue\\\/\",\"name\":\"dialogue Archives - Arcanoria Games\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/tag\\\/dialogue\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/tag\\\/dialogue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dialogue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/#website\",\"url\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/\",\"name\":\"Arcanoria Games\",\"description\":\"Interactive Storytellers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arcanoria.com\\\/games\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dialogue Archives - Arcanoria Games","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/","og_locale":"en_US","og_type":"article","og_title":"dialogue Archives - Arcanoria Games","og_url":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/","og_site_name":"Arcanoria Games","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/","url":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/","name":"dialogue Archives - Arcanoria Games","isPartOf":{"@id":"https:\/\/www.arcanoria.com\/games\/#website"},"breadcrumb":{"@id":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arcanoria.com\/games\/tag\/dialogue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arcanoria.com\/games\/"},{"@type":"ListItem","position":2,"name":"dialogue"}]},{"@type":"WebSite","@id":"https:\/\/www.arcanoria.com\/games\/#website","url":"https:\/\/www.arcanoria.com\/games\/","name":"Arcanoria Games","description":"Interactive Storytellers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arcanoria.com\/games\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.arcanoria.com\/games\/wp-json\/wp\/v2\/tags\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arcanoria.com\/games\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.arcanoria.com\/games\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.arcanoria.com\/games\/wp-json\/wp\/v2\/posts?tags=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}